{"id":17530,"date":"2024-09-09T09:42:47","date_gmt":"2024-09-09T16:42:47","guid":{"rendered":"https:\/\/centralialaw.com\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/"},"modified":"2025-05-30T12:11:06","modified_gmt":"2025-05-30T19:11:06","slug":"la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil","status":"publish","type":"post","link":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/","title":{"rendered":"La nueva Ley de Washington elimina las limitaciones del abuso sexual infantil"},"content":{"rendered":"\n<p>El 6 de junio de 2024 entr\u00f3 en vigor en el Estado de Washington una nueva ley que elimina el plazo de prescripci\u00f3n para presentar una demanda de resarcimiento de da\u00f1os y perjuicios por lesiones sufridas como consecuencia de abusos sexuales en la infancia cuando el acto de abuso sexual en la infancia se produzca a partir del 6 de junio de 2024.  <\/p>\n\n<p>Antes de la entrada en vigor de la ley, en caso de abuso sexual infantil, el plazo de prescripci\u00f3n de las acciones civiles por da\u00f1os y perjuicios era<br\/>la fecha posterior de las tres siguientes: tres a\u00f1os a partir de la comisi\u00f3n del acto que supuestamente caus\u00f3 la lesi\u00f3n o afecci\u00f3n; tres a\u00f1os a partir del momento en que la v\u00edctima descubri\u00f3 o deber\u00eda haber descubierto razonablemente que la lesi\u00f3n o afecci\u00f3n fue causada por el acto; o tres a\u00f1os a partir del momento en que la v\u00edctima descubri\u00f3 que el acto caus\u00f3 la lesi\u00f3n por la que se presenta la demanda.<\/p>\n\n<p>Los intentos anteriores de aprobar la ley (con car\u00e1cter retroactivo y prospectivo) hab\u00edan fracasado repetidamente en la C\u00e1mara Estatal. Se aprob\u00f3 una enmienda del representante estatal Peter Abbarno (republicano de Centralia) para eliminar la prescripci\u00f3n de forma prospectiva a partir de junio de 2024, junto con <a href=\"https:\/\/app.leg.wa.gov\/billsummary?billnumber=1618&amp;year=2024&amp;initiative=False\">la HB 1618.<\/a> <\/p>\n\n<p><\/p>\n\n<p><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 6 de junio de 2024 entr\u00f3 en vigor en el Estado de Washington una nueva ley que elimina el plazo de prescripci\u00f3n para presentar una demanda de resarcimiento de da\u00f1os y perjuicios por lesiones sufridas como consecuencia de abusos sexuales en la infancia cuando el acto de abuso sexual en la infancia se produzca [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17489,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[421],"tags":[440,443,442,369,407,441],"class_list":["post-17530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-abogados-cerca-de-ti","tag-abogados-penalistas","tag-abuso-sexual","tag-abuso-sexual-infantil","tag-centralia-es","tag-chehalis-es","tag-washington-abogados"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La nueva Ley de Washington elimina las limitaciones del abuso sexual infantil - Ley Centralia<\/title>\n<meta name=\"description\" content=\"Los abogados de Washington de Althauser Rayan Abbarno informaron de que se elimin\u00f3 prospectivamente la prescripci\u00f3n para los casos de abusos sexuales a menores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eliminaci\u00f3n de la prescripci\u00f3n del abuso sexual infantil\" \/>\n<meta property=\"og:description\" content=\"Los abogados de Washington de Althauser Rayan Abbarno informaron de que se elimin\u00f3 prospectivamente la prescripci\u00f3n para los casos de abusos sexuales a menores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/\" \/>\n<meta property=\"og:site_name\" content=\"Ley Centralia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlthauserRayanAbbarno\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-09T16:42:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-30T19:11:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centralialaw.com\/wp-content\/uploads\/2024\/09\/Child-Abuse-SOL.jpeg\" \/>\n<meta name=\"author\" content=\"Peter Abbarno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Eliminaci\u00f3n de la prescripci\u00f3n del abuso sexual infantil\" \/>\n<meta name=\"twitter:description\" content=\"Los abogados de Washington de Althauser Rayan Abbarno informaron de que se elimin\u00f3 prospectivamente la prescripci\u00f3n para los casos de abusos sexuales a menores.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/centralialaw.com\/wp-content\/uploads\/2024\/09\/Child-Abuse-SOL.jpeg\" \/>\n<meta name=\"twitter:creator\" content=\"@PeterAbbarno\" \/>\n<meta name=\"twitter:site\" content=\"@PeterAbbarno\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Peter Abbarno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/\"},\"author\":{\"name\":\"Peter Abbarno\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#\\\/schema\\\/person\\\/df75a746547e7cef043297aef1bbba38\"},\"headline\":\"La nueva Ley de Washington elimina las limitaciones del abuso sexual infantil\",\"datePublished\":\"2024-09-09T16:42:47+00:00\",\"dateModified\":\"2025-05-30T19:11:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/\"},\"wordCount\":239,\"publisher\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Child-Abuse-SOL.jpeg\",\"keywords\":[\"Abogados Penalistas\",\"Abuso sexual\",\"Abuso sexual infantil\",\"Centralia\",\"Chehalis\",\"Washington Abogados\"],\"articleSection\":[\"Abogados cerca de ti\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/\",\"url\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/\",\"name\":\"La nueva Ley de Washington elimina las limitaciones del abuso sexual infantil - Ley Centralia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Child-Abuse-SOL.jpeg\",\"datePublished\":\"2024-09-09T16:42:47+00:00\",\"dateModified\":\"2025-05-30T19:11:06+00:00\",\"description\":\"Los abogados de Washington de Althauser Rayan Abbarno informaron de que se elimin\u00f3 prospectivamente la prescripci\u00f3n para los casos de abusos sexuales a menores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Child-Abuse-SOL.jpeg\",\"contentUrl\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Child-Abuse-SOL.jpeg\",\"width\":474,\"height\":314,\"caption\":\"Hope Cards improved by Washington State Legislature. Althauser Rayan Abbarno explains.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nueva Ley de Washington elimina las limitaciones del abuso sexual infantil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/\",\"name\":\"Centralia Law\",\"description\":\"Al servicio del estado de Washington desde hace m\u00e1s de 75 a\u00f1os - Althauser Rayan Abbarno \",\"publisher\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#organization\",\"name\":\"Ley Centralia\",\"url\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ARA-Logo.png\",\"contentUrl\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ARA-Logo.png\",\"width\":1153,\"height\":364,\"caption\":\"Ley Centralia\"},\"image\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlthauserRayanAbbarno\\\/\",\"https:\\\/\\\/x.com\\\/PeterAbbarno\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#\\\/schema\\\/person\\\/df75a746547e7cef043297aef1bbba38\",\"name\":\"Peter Abbarno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4abfe3b7079121d1f28bfcee302a24a00532f113ebafa311593e0ebac2982d3b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4abfe3b7079121d1f28bfcee302a24a00532f113ebafa311593e0ebac2982d3b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4abfe3b7079121d1f28bfcee302a24a00532f113ebafa311593e0ebac2982d3b?s=96&d=mm&r=g\",\"caption\":\"Peter Abbarno\"},\"url\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/author\\\/peter-abbarno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nueva Ley de Washington elimina las limitaciones del abuso sexual infantil - Ley Centralia","description":"Los abogados de Washington de Althauser Rayan Abbarno informaron de que se elimin\u00f3 prospectivamente la prescripci\u00f3n para los casos de abusos sexuales a menores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/","og_locale":"es_ES","og_type":"article","og_title":"Eliminaci\u00f3n de la prescripci\u00f3n del abuso sexual infantil","og_description":"Los abogados de Washington de Althauser Rayan Abbarno informaron de que se elimin\u00f3 prospectivamente la prescripci\u00f3n para los casos de abusos sexuales a menores.","og_url":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/","og_site_name":"Ley Centralia","article_publisher":"https:\/\/www.facebook.com\/AlthauserRayanAbbarno\/","article_published_time":"2024-09-09T16:42:47+00:00","article_modified_time":"2025-05-30T19:11:06+00:00","og_image":[{"url":"https:\/\/centralialaw.com\/wp-content\/uploads\/2024\/09\/Child-Abuse-SOL.jpeg","type":"","width":"","height":""}],"author":"Peter Abbarno","twitter_card":"summary_large_image","twitter_title":"Eliminaci\u00f3n de la prescripci\u00f3n del abuso sexual infantil","twitter_description":"Los abogados de Washington de Althauser Rayan Abbarno informaron de que se elimin\u00f3 prospectivamente la prescripci\u00f3n para los casos de abusos sexuales a menores.","twitter_image":"https:\/\/centralialaw.com\/wp-content\/uploads\/2024\/09\/Child-Abuse-SOL.jpeg","twitter_creator":"@PeterAbbarno","twitter_site":"@PeterAbbarno","twitter_misc":{"Written by":"Peter Abbarno","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/#article","isPartOf":{"@id":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/"},"author":{"name":"Peter Abbarno","@id":"https:\/\/centralialaw.com\/es\/#\/schema\/person\/df75a746547e7cef043297aef1bbba38"},"headline":"La nueva Ley de Washington elimina las limitaciones del abuso sexual infantil","datePublished":"2024-09-09T16:42:47+00:00","dateModified":"2025-05-30T19:11:06+00:00","mainEntityOfPage":{"@id":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/"},"wordCount":239,"publisher":{"@id":"https:\/\/centralialaw.com\/es\/#organization"},"image":{"@id":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/#primaryimage"},"thumbnailUrl":"https:\/\/centralialaw.com\/wp-content\/uploads\/2024\/09\/Child-Abuse-SOL.jpeg","keywords":["Abogados Penalistas","Abuso sexual","Abuso sexual infantil","Centralia","Chehalis","Washington Abogados"],"articleSection":["Abogados cerca de ti"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/","url":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/","name":"La nueva Ley de Washington elimina las limitaciones del abuso sexual infantil - Ley Centralia","isPartOf":{"@id":"https:\/\/centralialaw.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/#primaryimage"},"image":{"@id":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/#primaryimage"},"thumbnailUrl":"https:\/\/centralialaw.com\/wp-content\/uploads\/2024\/09\/Child-Abuse-SOL.jpeg","datePublished":"2024-09-09T16:42:47+00:00","dateModified":"2025-05-30T19:11:06+00:00","description":"Los abogados de Washington de Althauser Rayan Abbarno informaron de que se elimin\u00f3 prospectivamente la prescripci\u00f3n para los casos de abusos sexuales a menores.","breadcrumb":{"@id":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/#primaryimage","url":"https:\/\/centralialaw.com\/wp-content\/uploads\/2024\/09\/Child-Abuse-SOL.jpeg","contentUrl":"https:\/\/centralialaw.com\/wp-content\/uploads\/2024\/09\/Child-Abuse-SOL.jpeg","width":474,"height":314,"caption":"Hope Cards improved by Washington State Legislature. Althauser Rayan Abbarno explains."},{"@type":"BreadcrumbList","@id":"https:\/\/centralialaw.com\/es\/la-nueva-ley-de-washington-elimina-las-limitaciones-del-abuso-sexual-infantil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/centralialaw.com\/es\/"},{"@type":"ListItem","position":2,"name":"La nueva Ley de Washington elimina las limitaciones del abuso sexual infantil"}]},{"@type":"WebSite","@id":"https:\/\/centralialaw.com\/es\/#website","url":"https:\/\/centralialaw.com\/es\/","name":"Centralia Law","description":"Al servicio del estado de Washington desde hace m\u00e1s de 75 a\u00f1os - Althauser Rayan Abbarno ","publisher":{"@id":"https:\/\/centralialaw.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centralialaw.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centralialaw.com\/es\/#organization","name":"Ley Centralia","url":"https:\/\/centralialaw.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centralialaw.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/centralialaw.com\/wp-content\/uploads\/2022\/05\/ARA-Logo.png","contentUrl":"https:\/\/centralialaw.com\/wp-content\/uploads\/2022\/05\/ARA-Logo.png","width":1153,"height":364,"caption":"Ley Centralia"},"image":{"@id":"https:\/\/centralialaw.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlthauserRayanAbbarno\/","https:\/\/x.com\/PeterAbbarno"]},{"@type":"Person","@id":"https:\/\/centralialaw.com\/es\/#\/schema\/person\/df75a746547e7cef043297aef1bbba38","name":"Peter Abbarno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4abfe3b7079121d1f28bfcee302a24a00532f113ebafa311593e0ebac2982d3b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4abfe3b7079121d1f28bfcee302a24a00532f113ebafa311593e0ebac2982d3b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4abfe3b7079121d1f28bfcee302a24a00532f113ebafa311593e0ebac2982d3b?s=96&d=mm&r=g","caption":"Peter Abbarno"},"url":"https:\/\/centralialaw.com\/es\/author\/peter-abbarno\/"}]}},"_links":{"self":[{"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/posts\/17530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/comments?post=17530"}],"version-history":[{"count":0,"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/posts\/17530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/media\/17489"}],"wp:attachment":[{"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/media?parent=17530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/categories?post=17530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/tags?post=17530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}