{"id":17710,"date":"2019-07-09T20:24:08","date_gmt":"2019-07-10T03:24:08","guid":{"rendered":"https:\/\/centralialaw.com\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/"},"modified":"2019-07-09T20:24:08","modified_gmt":"2019-07-10T03:24:08","slug":"abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja","status":"publish","type":"post","link":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/","title":{"rendered":"Abogados locales apoyan la campa\u00f1a de recogida de suministros de la Escuelita Roja"},"content":{"rendered":"<p>El bufete de abogados<a href=\"https:\/\/centralialaw.com\/es\/\"> Althauser Rayan Abbarno<\/a> apoya este a\u00f1o la campa\u00f1a<a href=\"http:\/\/www.redschool.org\"> Little Red Schoolhouse<\/a> Supply Drive, aportando 1.000 d\u00f3lares de donativos a la organizaci\u00f3n en el marat\u00f3n televisivo KXXO Mixx 96.1 del 9 de agosto.<\/p>\n<p>\u201cTodos los ni\u00f1os de nuestra comunidad merecen los materiales necesarios para tener \u00e9xito en la escuela\u201d, dijo Peter Abbarno, abogado y socio de Althauser Rayan Abbarno. \u201cUno de nuestros valores fundamentales es marcar la diferencia devolviendo y apoyando las oportunidades educativas. Nuestro despacho tambi\u00e9n lidera la campa\u00f1a de recogida de material escolar de Centralia\u201d. <\/p>\n<div id=\"attachment_7488\" style=\"width: 253px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/centralialaw.com\/wp-content\/uploads\/2019\/07\/LRS.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7488\" class=\" wp-image-7488\" src=\"https:\/\/centralialaw.com\/wp-content\/uploads\/2019\/07\/LRS-300x221.jpg\" alt=\"Althauser Rayan Abbarno patrocina la campa\u00f1a de recogida de material escolar Little Red Schoolhouse Back to School.\" width=\"243\" height=\"179\"><\/a><p id=\"caption-attachment-7488\" class=\"wp-caption-text\">Althauser Rayan Abbarno patrocina la campa\u00f1a de recogida de material escolar Little Red Schoolhouse Back to School.<\/p><\/div>\n<p>El 9 de agosto, la radio <a href=\"http:\/\/www.kxxo.com\">KXXO MIxx 96.1<\/a> organizar\u00e1 un marat\u00f3n de 12 horas. Personalidades en antena estar\u00e1n en la esquina de State y Washington, en el centro de Olympia, pidiendo donativos. <\/p>\n<p>Los abogados de Althauser Rayan Abbarno har\u00e1n una aparici\u00f3n para igualar hasta 1.000,00 $ de las donaciones de los oyentes de KXXO.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abNuestros abogados y nuestro personal creen en marcar la diferencia retribuyendo a las comunidades en las que vivimos, trabajamos y jugamos\u00bb, dijo Todd Rayan, abogado y socio de Althauser Rayan Abbarno. \u00abNos encanta tener oportunidades de retribuir y apreciamos   <a href=\"https:\/\/centralialaw.com\/wp-content\/uploads\/2019\/04\/DSC08638.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4558 alignleft\" src=\"https:\/\/centralialaw.com\/wp-content\/uploads\/2019\/04\/DSC08638-200x300.jpg\" alt=\"\" width=\"117\" height=\"176\"><\/a>la relaci\u00f3n con KXXO Mixx 96.1. Nuestra oficina tambi\u00e9n patrocina el concurso matinal Tribond a las 7:40 y patrocina la Campa\u00f1a Navide\u00f1a de Recogida de Juguetes\u00bb. <\/p>\n<p>El Proyecto Little Red Schoolhouse distribuir\u00e1 los suministros el 15 de agosto, de 8 a 18 h, en la Escuela Secundaria Komachin de Lacey. Para m\u00e1s informaci\u00f3n o para hacer donativos, visita www.redschool.com. <\/p>\n<p><a href=\"https:\/\/centralialaw.com\/wp-content\/uploads\/2019\/07\/school.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7491 alignleft\" src=\"https:\/\/centralialaw.com\/wp-content\/uploads\/2019\/07\/school-204x300.jpg\" alt=\"\" width=\"76\" height=\"112\"><\/a>Althauser Rayan Abbarno lleva representando a particulares y empresas de nuestra comunidad desde 1946. Para reunirte con su abogado en Olympia en Pervical Landing o en Centralia en el centro hist\u00f3rico, llama al (360) 754-5844 o visita Centralialaw.com <\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El bufete de abogados Althauser Rayan Abbarno apoya este a\u00f1o la campa\u00f1a Little Red Schoolhouse Supply Drive, aportando 1.000 d\u00f3lares de donativos a la organizaci\u00f3n en el marat\u00f3n televisivo KXXO Mixx 96.1 del 9 de agosto. \u201cTodos los ni\u00f1os de nuestra comunidad merecen los materiales necesarios para tener \u00e9xito en la escuela\u201d, dijo Peter Abbarno, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[406],"tags":[371,389,506,369,625,372,626],"class_list":["post-17710","post","type-post","status-publish","format-standard","hentry","category-articulos-2","tag-abogado-es","tag-abogado-es-2","tag-accionamiento-de-suministro","tag-centralia-es","tag-educacion","tag-olimpia","tag-pequena-escuela-roja"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abogados locales apoyan la campa\u00f1a de recogida de suministros de la Escuelita Roja - Ley Centralia<\/title>\n<meta name=\"description\" content=\"Las oficinas legales de Althauser Rayan Abbarno est\u00e1n apoyando la Little Red Schoolhouse Supply Drive este a\u00f1o igualando $1,000.00 de donaciones a la organizaci\u00f3n. Abogados de Olympia y Centralia cerca de ti en (360) 754-5844 o CentraliaLaw.com\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abogados locales apoyan la campa\u00f1a de recogida de suministros de la Escuelita Roja - Ley Centralia\" \/>\n<meta property=\"og:description\" content=\"Las oficinas legales de Althauser Rayan Abbarno est\u00e1n apoyando la Little Red Schoolhouse Supply Drive este a\u00f1o igualando $1,000.00 de donaciones a la organizaci\u00f3n. Abogados de Olympia y Centralia cerca de ti en (360) 754-5844 o CentraliaLaw.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/\" \/>\n<meta property=\"og:site_name\" content=\"Ley Centralia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlthauserRayanAbbarno\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-10T03:24:08+00:00\" \/>\n<meta name=\"author\" content=\"silveragency\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PeterAbbarno\" \/>\n<meta name=\"twitter:site\" content=\"@PeterAbbarno\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"silveragency\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/\"},\"author\":{\"name\":\"silveragency\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#\\\/schema\\\/person\\\/c90a306e6cec19446363bb73622e38f0\"},\"headline\":\"Abogados locales apoyan la campa\u00f1a de recogida de suministros de la Escuelita Roja\",\"datePublished\":\"2019-07-10T03:24:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/\"},\"wordCount\":329,\"publisher\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/LRS-300x221.jpg\",\"keywords\":[\"Abogado\",\"Abogado\",\"Accionamiento de suministro\",\"Centralia\",\"Educaci\u00f3n\",\"Olimpia\",\"Peque\u00f1a escuela roja\"],\"articleSection\":[\"Art\u00edculos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/\",\"url\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/\",\"name\":\"Abogados locales apoyan la campa\u00f1a de recogida de suministros de la Escuelita Roja - Ley Centralia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/LRS-300x221.jpg\",\"datePublished\":\"2019-07-10T03:24:08+00:00\",\"description\":\"Las oficinas legales de Althauser Rayan Abbarno est\u00e1n apoyando la Little Red Schoolhouse Supply Drive este a\u00f1o igualando $1,000.00 de donaciones a la organizaci\u00f3n. Abogados de Olympia y Centralia cerca de ti en (360) 754-5844 o CentraliaLaw.com\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/LRS-300x221.jpg\",\"contentUrl\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/LRS-300x221.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abogados locales apoyan la campa\u00f1a de recogida de suministros de la Escuelita Roja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/\",\"name\":\"Centralia Law\",\"description\":\"Al servicio del estado de Washington desde hace m\u00e1s de 75 a\u00f1os - Althauser Rayan Abbarno \",\"publisher\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#organization\",\"name\":\"Ley Centralia\",\"url\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ARA-Logo.png\",\"contentUrl\":\"https:\\\/\\\/centralialaw.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ARA-Logo.png\",\"width\":1153,\"height\":364,\"caption\":\"Ley Centralia\"},\"image\":{\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlthauserRayanAbbarno\\\/\",\"https:\\\/\\\/x.com\\\/PeterAbbarno\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/#\\\/schema\\\/person\\\/c90a306e6cec19446363bb73622e38f0\",\"name\":\"silveragency\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4651f4f7a0b935cb1de39e18a57f11b714fe08c8958a68707e471418252972e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4651f4f7a0b935cb1de39e18a57f11b714fe08c8958a68707e471418252972e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4651f4f7a0b935cb1de39e18a57f11b714fe08c8958a68707e471418252972e5?s=96&d=mm&r=g\",\"caption\":\"silveragency\"},\"sameAs\":[\"http:\\\/\\\/centralialaw.com\"],\"url\":\"https:\\\/\\\/centralialaw.com\\\/es\\\/author\\\/silveragency\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abogados locales apoyan la campa\u00f1a de recogida de suministros de la Escuelita Roja - Ley Centralia","description":"Las oficinas legales de Althauser Rayan Abbarno est\u00e1n apoyando la Little Red Schoolhouse Supply Drive este a\u00f1o igualando $1,000.00 de donaciones a la organizaci\u00f3n. Abogados de Olympia y Centralia cerca de ti en (360) 754-5844 o CentraliaLaw.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/","og_locale":"es_ES","og_type":"article","og_title":"Abogados locales apoyan la campa\u00f1a de recogida de suministros de la Escuelita Roja - Ley Centralia","og_description":"Las oficinas legales de Althauser Rayan Abbarno est\u00e1n apoyando la Little Red Schoolhouse Supply Drive este a\u00f1o igualando $1,000.00 de donaciones a la organizaci\u00f3n. Abogados de Olympia y Centralia cerca de ti en (360) 754-5844 o CentraliaLaw.com","og_url":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/","og_site_name":"Ley Centralia","article_publisher":"https:\/\/www.facebook.com\/AlthauserRayanAbbarno\/","article_published_time":"2019-07-10T03:24:08+00:00","author":"silveragency","twitter_card":"summary_large_image","twitter_creator":"@PeterAbbarno","twitter_site":"@PeterAbbarno","twitter_misc":{"Written by":"silveragency","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/#article","isPartOf":{"@id":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/"},"author":{"name":"silveragency","@id":"https:\/\/centralialaw.com\/es\/#\/schema\/person\/c90a306e6cec19446363bb73622e38f0"},"headline":"Abogados locales apoyan la campa\u00f1a de recogida de suministros de la Escuelita Roja","datePublished":"2019-07-10T03:24:08+00:00","mainEntityOfPage":{"@id":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/"},"wordCount":329,"publisher":{"@id":"https:\/\/centralialaw.com\/es\/#organization"},"image":{"@id":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/#primaryimage"},"thumbnailUrl":"https:\/\/centralialaw.com\/wp-content\/uploads\/2019\/07\/LRS-300x221.jpg","keywords":["Abogado","Abogado","Accionamiento de suministro","Centralia","Educaci\u00f3n","Olimpia","Peque\u00f1a escuela roja"],"articleSection":["Art\u00edculos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/","url":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/","name":"Abogados locales apoyan la campa\u00f1a de recogida de suministros de la Escuelita Roja - Ley Centralia","isPartOf":{"@id":"https:\/\/centralialaw.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/#primaryimage"},"image":{"@id":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/#primaryimage"},"thumbnailUrl":"https:\/\/centralialaw.com\/wp-content\/uploads\/2019\/07\/LRS-300x221.jpg","datePublished":"2019-07-10T03:24:08+00:00","description":"Las oficinas legales de Althauser Rayan Abbarno est\u00e1n apoyando la Little Red Schoolhouse Supply Drive este a\u00f1o igualando $1,000.00 de donaciones a la organizaci\u00f3n. Abogados de Olympia y Centralia cerca de ti en (360) 754-5844 o CentraliaLaw.com","breadcrumb":{"@id":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/#primaryimage","url":"https:\/\/centralialaw.com\/wp-content\/uploads\/2019\/07\/LRS-300x221.jpg","contentUrl":"https:\/\/centralialaw.com\/wp-content\/uploads\/2019\/07\/LRS-300x221.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/centralialaw.com\/es\/abogados-locales-apoyan-la-campana-de-recogida-de-suministros-de-la-escuelita-roja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/centralialaw.com\/es\/"},{"@type":"ListItem","position":2,"name":"Abogados locales apoyan la campa\u00f1a de recogida de suministros de la Escuelita Roja"}]},{"@type":"WebSite","@id":"https:\/\/centralialaw.com\/es\/#website","url":"https:\/\/centralialaw.com\/es\/","name":"Centralia Law","description":"Al servicio del estado de Washington desde hace m\u00e1s de 75 a\u00f1os - Althauser Rayan Abbarno ","publisher":{"@id":"https:\/\/centralialaw.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centralialaw.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centralialaw.com\/es\/#organization","name":"Ley Centralia","url":"https:\/\/centralialaw.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centralialaw.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/centralialaw.com\/wp-content\/uploads\/2022\/05\/ARA-Logo.png","contentUrl":"https:\/\/centralialaw.com\/wp-content\/uploads\/2022\/05\/ARA-Logo.png","width":1153,"height":364,"caption":"Ley Centralia"},"image":{"@id":"https:\/\/centralialaw.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlthauserRayanAbbarno\/","https:\/\/x.com\/PeterAbbarno"]},{"@type":"Person","@id":"https:\/\/centralialaw.com\/es\/#\/schema\/person\/c90a306e6cec19446363bb73622e38f0","name":"silveragency","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4651f4f7a0b935cb1de39e18a57f11b714fe08c8958a68707e471418252972e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4651f4f7a0b935cb1de39e18a57f11b714fe08c8958a68707e471418252972e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4651f4f7a0b935cb1de39e18a57f11b714fe08c8958a68707e471418252972e5?s=96&d=mm&r=g","caption":"silveragency"},"sameAs":["http:\/\/centralialaw.com"],"url":"https:\/\/centralialaw.com\/es\/author\/silveragency\/"}]}},"_links":{"self":[{"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/posts\/17710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/comments?post=17710"}],"version-history":[{"count":0,"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/posts\/17710\/revisions"}],"wp:attachment":[{"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/media?parent=17710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/categories?post=17710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centralialaw.com\/es\/wp-json\/wp\/v2\/tags?post=17710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}